{"id":58157,"date":"2025-09-12T09:55:32","date_gmt":"2025-09-12T07:55:32","guid":{"rendered":"https:\/\/www.maisonschwind.lu\/product\/viscose-serpent-22301998\/"},"modified":"2026-05-01T09:02:47","modified_gmt":"2026-05-01T07:02:47","slug":"viscose-serpent-22301998","status":"publish","type":"product","link":"https:\/\/www.maisonschwind.lu\/fr\/produit\/viscose-serpent-22301998\/","title":{"rendered":"Viscose serpent 22301998"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"58157\" class=\"elementor elementor-58157 elementor-58015\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-10749cc8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"10749cc8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3391f45a\" data-id=\"3391f45a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-241e0352 elementor-widget elementor-widget-text-editor\" data-id=\"241e0352\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.6.7 - 03-07-2022 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p><img loading=\"lazy\" class=\"size-full wp-image-58016 aligncenter\" src=\"https:\/\/www.maisonschwind.lu\/shop\/wp-content\/uploads\/2025\/09\/OEKOTEX-CLASS-2-BLACK-SM-WEBP_400x400-3.webp\" alt=\"\" width=\"300\" height=\"174\" \/><\/p><p><img loading=\"lazy\" class=\"size-full wp-image-58032 aligncenter\" src=\"https:\/\/www.maisonschwind.lu\/shop\/wp-content\/uploads\/2025\/09\/wasvoorschrift-09-1.webp\" alt=\"\" width=\"284\" height=\"43\" \/><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>55% viscose 45% polyester<\/p>\n<p>105 gr<\/p>\n<p>Largeur 145 cm<\/p>\n<p>Quantit\u00e9 1 = 10 cm<\/p>\n","protected":false},"featured_media":58028,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_cat":[1560,1450,1452],"product_tag":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.maisonschwind.lu\/fr\/wp-json\/wp\/v2\/product\/58157"}],"collection":[{"href":"https:\/\/www.maisonschwind.lu\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.maisonschwind.lu\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.maisonschwind.lu\/fr\/wp-json\/wp\/v2\/comments?post=58157"}],"version-history":[{"count":1,"href":"https:\/\/www.maisonschwind.lu\/fr\/wp-json\/wp\/v2\/product\/58157\/revisions"}],"predecessor-version":[{"id":58160,"href":"https:\/\/www.maisonschwind.lu\/fr\/wp-json\/wp\/v2\/product\/58157\/revisions\/58160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.maisonschwind.lu\/fr\/wp-json\/wp\/v2\/media\/58028"}],"wp:attachment":[{"href":"https:\/\/www.maisonschwind.lu\/fr\/wp-json\/wp\/v2\/media?parent=58157"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.maisonschwind.lu\/fr\/wp-json\/wp\/v2\/product_cat?post=58157"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.maisonschwind.lu\/fr\/wp-json\/wp\/v2\/product_tag?post=58157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}