{"id":66802,"date":"2026-03-25T17:14:29","date_gmt":"2026-03-25T16:14:29","guid":{"rendered":"https:\/\/www.maisonschwind.lu\/product\/viscose-radiance-digital-08046-001\/"},"modified":"2026-03-27T11:56:38","modified_gmt":"2026-03-27T10:56:38","slug":"viscose-radiance-digital-08046-001","status":"publish","type":"product","link":"https:\/\/www.maisonschwind.lu\/fr\/produit\/viscose-radiance-digital-08046-001\/","title":{"rendered":"Viscose radiance digital 08046.001"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"66802\" class=\"elementor elementor-66802 elementor-66577\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-10749cc8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"10749cc8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3391f45a\" data-id=\"3391f45a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-241e0352 elementor-widget elementor-widget-text-editor\" data-id=\"241e0352\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.6.7 - 03-07-2022 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>\u00a0<img loading=\"lazy\" class=\"size-medium wp-image-66580 aligncenter\" src=\"https:\/\/www.maisonschwind.lu\/shop\/wp-content\/uploads\/2026\/03\/trichlo-trumble-dry-300x255.jpg\" alt=\"\" width=\"300\" height=\"255\" srcset=\"https:\/\/www.maisonschwind.lu\/shop\/wp-content\/uploads\/2026\/03\/trichlo-trumble-dry-300x255.jpg 300w, https:\/\/www.maisonschwind.lu\/shop\/wp-content\/uploads\/2026\/03\/trichlo-trumble-dry.jpg 395w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>100% viscose<\/p>\n<p>110gr<\/p>\n<p>Largeur : 140 cm<\/p>\n<p>Quantit\u00e9 1 = 10cm<\/p>\n","protected":false},"featured_media":66542,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_cat":[1492,1562,1452],"product_tag":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.maisonschwind.lu\/fr\/wp-json\/wp\/v2\/product\/66802"}],"collection":[{"href":"https:\/\/www.maisonschwind.lu\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.maisonschwind.lu\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.maisonschwind.lu\/fr\/wp-json\/wp\/v2\/comments?post=66802"}],"version-history":[{"count":1,"href":"https:\/\/www.maisonschwind.lu\/fr\/wp-json\/wp\/v2\/product\/66802\/revisions"}],"predecessor-version":[{"id":66804,"href":"https:\/\/www.maisonschwind.lu\/fr\/wp-json\/wp\/v2\/product\/66802\/revisions\/66804"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.maisonschwind.lu\/fr\/wp-json\/wp\/v2\/media\/66542"}],"wp:attachment":[{"href":"https:\/\/www.maisonschwind.lu\/fr\/wp-json\/wp\/v2\/media?parent=66802"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.maisonschwind.lu\/fr\/wp-json\/wp\/v2\/product_cat?post=66802"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.maisonschwind.lu\/fr\/wp-json\/wp\/v2\/product_tag?post=66802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}